{"id":82920,"date":"2019-07-30T19:21:46","date_gmt":"2019-07-30T17:21:46","guid":{"rendered":"https:\/\/ueberraum.co\/?p=82920"},"modified":"2026-02-23T17:44:24","modified_gmt":"2026-02-23T16:44:24","slug":"fotograf-002","status":"publish","type":"post","link":"https:\/\/ueberraum.co\/en\/fotograf-002\/","title":{"rendered":"Florian Zenk &#8211; Fotograf"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-0\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text bottom-t-top animate_when_almost_visible\" data-delay=\"400\"><h2 class=\"h2\" ><span>Florian Zenk &#8211; Fotograf<\/span><\/h2><div><p>Wenn Florian Zenk fotografiert, ist das f\u00fcr ihn das gr\u00f6\u00dfte Gef\u00fchl von Freiheit. Dazu kommt seine ausgepr\u00e4gte Neugier auf Menschen, neue Orte, Situationen und Unbekanntes. Mit dieser Neugier und der Freiheit kann er seine ganze Kreativit\u00e4t entfalten und in seine Kunst \u00fcbersetzen. Neben Events fotografiert er auch liebend gerne Familien, Babyb\u00e4uche &amp; Neugeborene, Hochzheiten und Architektur und Minimalismus.<\/p>\n<p>Hochzeit - Event - Real Estate<\/p>\n<\/div><\/div><div class=\"clear\"><\/div><\/div><div id=\"gallery-807586\" class=\"un-media-gallery isotope-system isotope-general-light grid-general-light\">\n\t\t\t\t\t\n\t\n\t<div class=\"isotope-wrapper grid-wrapper single-gutter\" >\n\t\t\t\t\t\t\t\t\t<div class=\"isotope-container isotope-layout style-masonry\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\">\n<div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-83123  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside animate_when_almost_visible bottom-t-top\" data-delay=\"100\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 150%;\"><\/div><a href=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/florianzenkphotography1119.jpg\"  class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-807586\" data-options=\"width:500,height:750,thumbnail: 'https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/florianzenkphotography1119-200x300.jpg'\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-83123\" src=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/florianzenkphotography1119.jpg\" width=\"500\" height=\"750\" alt=\"\" srcset=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/florianzenkphotography1119.jpg 500w, https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/florianzenkphotography1119-200x300.jpg 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-83124  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside animate_when_almost_visible bottom-t-top\" data-delay=\"100\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 66.7%;\"><\/div><a href=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/McKinseyxKronbergxflorianzenk.com-1.jpg\"  class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-807586\" data-options=\"width:1000,height:667,thumbnail: 'https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/McKinseyxKronbergxflorianzenk.com-1-300x200.jpg'\" data-lb-index=\"1\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-83124\" src=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/McKinseyxKronbergxflorianzenk.com-1.jpg\" width=\"1000\" height=\"667\" alt=\"\" srcset=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/McKinseyxKronbergxflorianzenk.com-1.jpg 1000w, https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/McKinseyxKronbergxflorianzenk.com-1-300x200.jpg 300w, https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/McKinseyxKronbergxflorianzenk.com-1-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-83125  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside animate_when_almost_visible bottom-t-top\" data-delay=\"100\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 150%;\"><\/div><a href=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/tivex.jpg\"  class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-807586\" data-options=\"width:500,height:750,thumbnail: 'https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/tivex-200x300.jpg'\" data-lb-index=\"2\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-83125\" src=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/tivex.jpg\" width=\"500\" height=\"750\" alt=\"\" srcset=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/tivex.jpg 500w, https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/tivex-200x300.jpg 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-83126  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside animate_when_almost_visible bottom-t-top\" data-delay=\"100\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 150%;\"><\/div><a href=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/IqosHHxMai2017xflorianzenkphotography-74.jpg\"  class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-807586\" data-options=\"width:500,height:750,thumbnail: 'https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/IqosHHxMai2017xflorianzenkphotography-74-200x300.jpg'\" data-lb-index=\"3\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-83126\" src=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/IqosHHxMai2017xflorianzenkphotography-74.jpg\" width=\"500\" height=\"750\" alt=\"\" srcset=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/IqosHHxMai2017xflorianzenkphotography-74.jpg 500w, https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/IqosHHxMai2017xflorianzenkphotography-74-200x300.jpg 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-83127  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside animate_when_almost_visible bottom-t-top\" data-delay=\"100\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 66.8%;\"><\/div><a href=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/florianzenk.com-23.jpg\"  class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-807586\" data-options=\"width:500,height:334,thumbnail: 'https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/florianzenk.com-23-300x200.jpg'\" data-lb-index=\"4\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-83127\" src=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/florianzenk.com-23.jpg\" width=\"500\" height=\"334\" alt=\"\" srcset=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/florianzenk.com-23.jpg 500w, https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/florianzenk.com-23-300x200.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-83128  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside animate_when_almost_visible bottom-t-top\" data-delay=\"100\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 66.8%;\"><\/div><a href=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/31048415645_2b70f312c5_o.jpg\"  class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-807586\" data-options=\"width:500,height:334,thumbnail: 'https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/31048415645_2b70f312c5_o-300x200.jpg'\" data-lb-index=\"5\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-83128\" src=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/31048415645_2b70f312c5_o.jpg\" width=\"500\" height=\"334\" alt=\"\" srcset=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/31048415645_2b70f312c5_o.jpg 500w, https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/31048415645_2b70f312c5_o-300x200.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-83129  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside animate_when_almost_visible bottom-t-top\" data-delay=\"100\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 66.6%;\"><\/div><a href=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/Sep2015xflorianzenkphotography-36.jpg\"  class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-807586\" data-options=\"width:500,height:333,thumbnail: 'https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/Sep2015xflorianzenkphotography-36-300x200.jpg'\" data-lb-index=\"6\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-83129\" src=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/Sep2015xflorianzenkphotography-36.jpg\" width=\"500\" height=\"333\" alt=\"\" srcset=\"https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/Sep2015xflorianzenkphotography-36.jpg 500w, https:\/\/ueberraum.co\/wp-content\/uploads\/2019\/07\/Sep2015xflorianzenkphotography-36-300x200.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\t\n\t\n<\/div>\n\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-0\" data-row=\"script-row-unique-0\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-0\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-1\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-3 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-6 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text left-t-right animate_when_almost_visible\" data-delay=\"400\"><h2 class=\"h2\" ><span><\/p><\/span><span><p style=\"text-align: center;\">Haben Sie fragen oder m\u00f6chten Sie diesen Fotografen buchen?<\/p><\/span><span><p><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f82718-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"82718\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/posts\/82920#wpcf7-f82718-o1\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/posts\/82920#wpcf7-f82718-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"82718\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f82718-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-fullname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-fluid\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"First and last name\" value=\"\" type=\"text\" name=\"your-fullname\" \/><\/span>\n<\/p>\n<div class=\"wpcf7-inline-wrapper\">\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-telephone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-fluid\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"text\" name=\"your-telephone\" \/><\/span>\n\t<\/p>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-640\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"menu-640\"><option value=\"Ich m\u00f6chte einen K\u00fcnstler buchen\">I want to book an artist<\/option><option value=\"Ich m\u00f6chte mehr Informationen zum K\u00fcnstler\">I would like more information about the artist<\/option><option value=\"Sonstige Anliegen\">Other concerns<\/option><\/select><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"8\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Who is the artist? (simply paste the link of this page here)\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"8\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Describe your request.\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p class=\"datenschutz\"><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"zustimmung-datenschutz\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"zustimmung-datenschutz\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I agree that my details from the contact form will be collected and processed to answer my request. Detailed information on how user data is handled can be found in our <a href=\"\/en\/data-protection\/\">Privacy Policy<\/a>.<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-color-prif btn-square\" type=\"submit\" value=\"Send inquiry\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-3 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-1\" data-row=\"script-row-unique-1\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-1\"));<\/script><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Florian Zenk - FotografWenn Florian Zenk fotografiert, ist das f\u00fcr ihn das gr\u00f6\u00dfte Gef\u00fchl von Freiheit. Dazu kommt seine ausgepr\u00e4gte [...]","protected":false},"author":1,"featured_media":83069,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[211,177],"tags":[],"class_list":["post-82920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artist-booking","category-fotografen"],"_links":{"self":[{"href":"https:\/\/ueberraum.co\/en\/wp-json\/wp\/v2\/posts\/82920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ueberraum.co\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ueberraum.co\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ueberraum.co\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ueberraum.co\/en\/wp-json\/wp\/v2\/comments?post=82920"}],"version-history":[{"count":2,"href":"https:\/\/ueberraum.co\/en\/wp-json\/wp\/v2\/posts\/82920\/revisions"}],"predecessor-version":[{"id":89977,"href":"https:\/\/ueberraum.co\/en\/wp-json\/wp\/v2\/posts\/82920\/revisions\/89977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ueberraum.co\/en\/wp-json\/wp\/v2\/media\/83069"}],"wp:attachment":[{"href":"https:\/\/ueberraum.co\/en\/wp-json\/wp\/v2\/media?parent=82920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ueberraum.co\/en\/wp-json\/wp\/v2\/categories?post=82920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ueberraum.co\/en\/wp-json\/wp\/v2\/tags?post=82920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}